{"id":27582,"date":"2024-12-04T18:08:07","date_gmt":"2024-12-04T15:08:07","guid":{"rendered":"https:\/\/head-beauty.com\/product\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/"},"modified":"2026-03-05T16:38:38","modified_gmt":"2026-03-05T13:38:38","slug":"sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic","status":"publish","type":"product","link":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/","title":{"rendered":"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic"},"content":{"rendered":"<p>Tijeras de cabeza peque\u00f1a de forma cl\u00e1sica adecuadas para principiantes y profesionales, f\u00e1cil de mover y usar, forma de anillo \u00f3ptima, mangos mate, rendimiento mejorado de la superficie para la desinfecci\u00f3n y esterilizaci\u00f3n regulares, afilado manual, per\u00edodo de trabajo m\u00e1s largo, alta ergonom\u00eda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tijeras de cabeza peque\u00f1a de forma cl\u00e1sica adecuadas para principiantes y profesionales, f\u00e1cil de mover y usar, forma de anillo \u00f3ptima, mangos mate, rendimiento mejorado de la superficie para la desinfecci\u00f3n y esterilizaci\u00f3n regulares, afilado manual, per\u00edodo de trabajo m\u00e1s largo, alta ergonom\u00eda<\/p>\n","protected":false},"featured_media":23628,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[358],"product_tag":[407],"class_list":{"0":"post-27582","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tijeras","7":"product_tag-tijeras-x-line","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic - Head Beauty<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic - Head Beauty\" \/>\n<meta property=\"og:description\" content=\"Tijeras de cabeza peque\u00f1a de forma cl\u00e1sica adecuadas para principiantes y profesionales, f\u00e1cil de mover y usar, forma de anillo \u00f3ptima, mangos mate, rendimiento mejorado de la superficie para la desinfecci\u00f3n y esterilizaci\u00f3n regulares, afilado manual, per\u00edodo de trabajo m\u00e1s largo, alta ergonom\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/\" \/>\n<meta property=\"og:site_name\" content=\"Head Beauty\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T13:38:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/\",\"url\":\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/\",\"name\":\"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic - Head Beauty\",\"isPartOf\":{\"@id\":\"https:\/\/head-beauty.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg\",\"datePublished\":\"2024-12-04T15:08:07+00:00\",\"dateModified\":\"2026-03-05T13:38:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#primaryimage\",\"url\":\"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg\",\"contentUrl\":\"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Tijeras de cabeza peque\u00f1a de forma cl\u00e1sica adecuadas para principiantes y profesionales, f\u00e1cil de mover y usar, forma de anillo \u00f3ptima, mangos mate, rendimiento mejorado de la superficie para la desinfecci\u00f3n y esterilizaci\u00f3n regulares, afilado manual, per\u00edodo de trabajo m\u00e1s largo, alta ergonom\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/head-beauty.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/head-beauty.com\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/head-beauty.com\/es\/#website\",\"url\":\"https:\/\/head-beauty.com\/es\/\",\"name\":\"Head - The Beauty Tools\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/head-beauty.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/head-beauty.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/head-beauty.com\/es\/#organization\",\"name\":\"Head - The Beauty Tools\",\"url\":\"https:\/\/head-beauty.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/head-beauty.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/10\/head-beauty-logo.svg\",\"contentUrl\":\"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/10\/head-beauty-logo.svg\",\"width\":411.20999999999997953636921010911464691162109375,\"height\":200,\"caption\":\"Head - The Beauty Tools\"},\"image\":{\"@id\":\"https:\/\/head-beauty.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic - Head Beauty","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/","og_locale":"es_ES","og_type":"article","og_title":"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic - Head Beauty","og_description":"Tijeras de cabeza peque\u00f1a de forma cl\u00e1sica adecuadas para principiantes y profesionales, f\u00e1cil de mover y usar, forma de anillo \u00f3ptima, mangos mate, rendimiento mejorado de la superficie para la desinfecci\u00f3n y esterilizaci\u00f3n regulares, afilado manual, per\u00edodo de trabajo m\u00e1s largo, alta ergonom\u00eda","og_url":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/","og_site_name":"Head Beauty","article_modified_time":"2026-03-05T13:38:38+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/","url":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/","name":"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic - Head Beauty","isPartOf":{"@id":"https:\/\/head-beauty.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#primaryimage"},"image":{"@id":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#primaryimage"},"thumbnailUrl":"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg","datePublished":"2024-12-04T15:08:07+00:00","dateModified":"2026-03-05T13:38:38+00:00","breadcrumb":{"@id":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#primaryimage","url":"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg","contentUrl":"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/12\/SX-101-1-scaled.jpg","width":2560,"height":2560,"caption":"Tijeras de cabeza peque\u00f1a de forma cl\u00e1sica adecuadas para principiantes y profesionales, f\u00e1cil de mover y usar, forma de anillo \u00f3ptima, mangos mate, rendimiento mejorado de la superficie para la desinfecci\u00f3n y esterilizaci\u00f3n regulares, afilado manual, per\u00edodo de trabajo m\u00e1s largo, alta ergonom\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/head-beauty.com\/es\/producto\/sx-101-tijeras-para-cuticulas-profesionales-x-line-hojas-16-mm-classic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/head-beauty.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/head-beauty.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"SX-101 Tijeras para cut\u00edculas profesionales X-line, hojas 16 mm, Classic"}]},{"@type":"WebSite","@id":"https:\/\/head-beauty.com\/es\/#website","url":"https:\/\/head-beauty.com\/es\/","name":"Head - The Beauty Tools","description":"","publisher":{"@id":"https:\/\/head-beauty.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/head-beauty.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/head-beauty.com\/es\/#organization","name":"Head - The Beauty Tools","url":"https:\/\/head-beauty.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/head-beauty.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/10\/head-beauty-logo.svg","contentUrl":"https:\/\/head-beauty.com\/wp-content\/uploads\/2024\/10\/head-beauty-logo.svg","width":411.20999999999997953636921010911464691162109375,"height":200,"caption":"Head - The Beauty Tools"},"image":{"@id":"https:\/\/head-beauty.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/product\/27582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/media\/23628"}],"wp:attachment":[{"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/media?parent=27582"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/product_brand?post=27582"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/product_cat?post=27582"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/head-beauty.com\/es\/wp-json\/wp\/v2\/product_tag?post=27582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}